{"id":3538,"count":1,"description":"1963.05.09.","link":"https:\/\/folkmedia.neptanc.ro\/ro\/eloadok\/hideg-ilona\/","name":"Hideg Ilona","slug":"hideg-ilona","taxonomy":"eloadok","meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/folkmedia.neptanc.ro\/ro\/wp-json\/wp\/v2\/eloadok\/3538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folkmedia.neptanc.ro\/ro\/wp-json\/wp\/v2\/eloadok"}],"about":[{"href":"https:\/\/folkmedia.neptanc.ro\/ro\/wp-json\/wp\/v2\/taxonomies\/eloadok"}],"wp:post_type":[{"href":"https:\/\/folkmedia.neptanc.ro\/ro\/wp-json\/wp\/v2\/posts?eloadok=3538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}