{"id":3539,"count":1,"description":"1930.11.06.","link":"https:\/\/folkmedia.neptanc.ro\/en\/eloadok\/gyori-daniel\/","name":"Gy\u0151ri D\u00e1niel","slug":"gyori-daniel","taxonomy":"eloadok","meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/folkmedia.neptanc.ro\/en\/wp-json\/wp\/v2\/eloadok\/3539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folkmedia.neptanc.ro\/en\/wp-json\/wp\/v2\/eloadok"}],"about":[{"href":"https:\/\/folkmedia.neptanc.ro\/en\/wp-json\/wp\/v2\/taxonomies\/eloadok"}],"wp:post_type":[{"href":"https:\/\/folkmedia.neptanc.ro\/en\/wp-json\/wp\/v2\/posts?eloadok=3539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}